{"id":271,"count":2,"description":"","link":"https:\/\/aqpa-indonesia.com\/id\/product-category\/product\/gasketing\/","name":"Gasket","slug":"gasketing","taxonomy":"product_cat","parent":229,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gasketing Archives - AQPA INDONESIA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aqpa-indonesia.com\/id\/product-category\/produk\/gasketing\/\" \/>\n<meta property=\"og:locale\" content=\"id_ID\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gasketing Archives - AQPA INDONESIA\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aqpa-indonesia.com\/id\/product-category\/produk\/gasketing\/\" \/>\n<meta property=\"og:site_name\" content=\"AQPA INDONESIA\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aqpa-indonesia.com\/wp-content\/uploads\/2025\/01\/AUTHORIZED-GTE-PRODUCT.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"1170\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/aqpa-indonesia.com\\\/product-category\\\/product\\\/gasketing\\\/\",\"url\":\"https:\\\/\\\/aqpa-indonesia.com\\\/product-category\\\/product\\\/gasketing\\\/\",\"name\":\"Gasketing Archives - AQPA INDONESIA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aqpa-indonesia.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aqpa-indonesia.com\\\/product-category\\\/product\\\/gasketing\\\/#breadcrumb\"},\"inLanguage\":\"id\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aqpa-indonesia.com\\\/product-category\\\/product\\\/gasketing\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/aqpa-indonesia.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Product\",\"item\":\"https:\\\/\\\/aqpa-indonesia.com\\\/product-category\\\/product\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gasketing\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aqpa-indonesia.com\\\/#website\",\"url\":\"https:\\\/\\\/aqpa-indonesia.com\\\/\",\"name\":\"AQPA INDONESIA\",\"description\":\"Aqpa Indonesia katalog product\",\"publisher\":{\"@id\":\"https:\\\/\\\/aqpa-indonesia.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aqpa-indonesia.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"id\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aqpa-indonesia.com\\\/#organization\",\"name\":\"AQPA INDONESIA\",\"url\":\"https:\\\/\\\/aqpa-indonesia.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"id\",\"@id\":\"https:\\\/\\\/aqpa-indonesia.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aqpa-indonesia.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-cropped-logo-new-e1714795698905.png\",\"contentUrl\":\"https:\\\/\\\/aqpa-indonesia.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-cropped-logo-new-e1714795698905.png\",\"width\":180,\"height\":60,\"caption\":\"AQPA INDONESIA\"},\"image\":{\"@id\":\"https:\\\/\\\/aqpa-indonesia.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=61576567931709\",\"https:\\\/\\\/www.instagram.com\\\/aqpaindonesiaofficial\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gasketing Archives - AQPA INDONESIA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aqpa-indonesia.com\/id\/product-category\/produk\/gasketing\/","og_locale":"id_ID","og_type":"article","og_title":"Gasketing Archives - AQPA INDONESIA","og_url":"https:\/\/aqpa-indonesia.com\/id\/product-category\/produk\/gasketing\/","og_site_name":"AQPA INDONESIA","og_image":[{"width":1170,"height":1170,"url":"https:\/\/aqpa-indonesia.com\/wp-content\/uploads\/2025\/01\/AUTHORIZED-GTE-PRODUCT.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/aqpa-indonesia.com\/product-category\/product\/gasketing\/","url":"https:\/\/aqpa-indonesia.com\/product-category\/product\/gasketing\/","name":"Gasketing Archives - AQPA INDONESIA","isPartOf":{"@id":"https:\/\/aqpa-indonesia.com\/#website"},"breadcrumb":{"@id":"https:\/\/aqpa-indonesia.com\/product-category\/product\/gasketing\/#breadcrumb"},"inLanguage":"id"},{"@type":"BreadcrumbList","@id":"https:\/\/aqpa-indonesia.com\/product-category\/product\/gasketing\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aqpa-indonesia.com\/"},{"@type":"ListItem","position":2,"name":"Product","item":"https:\/\/aqpa-indonesia.com\/product-category\/product\/"},{"@type":"ListItem","position":3,"name":"Gasketing"}]},{"@type":"WebSite","@id":"https:\/\/aqpa-indonesia.com\/#website","url":"https:\/\/aqpa-indonesia.com\/","name":"AQPA INDONESIA","description":"Aqpa Indonesia katalog product","publisher":{"@id":"https:\/\/aqpa-indonesia.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aqpa-indonesia.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"id"},{"@type":"Organization","@id":"https:\/\/aqpa-indonesia.com\/#organization","name":"AQPA INDONESIA","url":"https:\/\/aqpa-indonesia.com\/","logo":{"@type":"ImageObject","inLanguage":"id","@id":"https:\/\/aqpa-indonesia.com\/#\/schema\/logo\/image\/","url":"https:\/\/aqpa-indonesia.com\/wp-content\/uploads\/2024\/05\/cropped-cropped-logo-new-e1714795698905.png","contentUrl":"https:\/\/aqpa-indonesia.com\/wp-content\/uploads\/2024\/05\/cropped-cropped-logo-new-e1714795698905.png","width":180,"height":60,"caption":"AQPA INDONESIA"},"image":{"@id":"https:\/\/aqpa-indonesia.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=61576567931709","https:\/\/www.instagram.com\/aqpaindonesiaofficial\/"]}]}},"_links":{"self":[{"href":"https:\/\/aqpa-indonesia.com\/id\/wp-json\/wp\/v2\/product_cat\/271","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aqpa-indonesia.com\/id\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/aqpa-indonesia.com\/id\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/aqpa-indonesia.com\/id\/wp-json\/wp\/v2\/product_cat\/229"}],"wp:post_type":[{"href":"https:\/\/aqpa-indonesia.com\/id\/wp-json\/wp\/v2\/product?product_cat=271"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}